{"id":4636,"date":"2023-11-08T11:56:15","date_gmt":"2023-11-08T11:56:15","guid":{"rendered":"https:\/\/agrupalmeria.com\/?p=4636"},"modified":"2024-01-17T13:17:28","modified_gmt":"2024-01-17T13:17:28","slug":"increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas","status":"publish","type":"post","link":"https:\/\/agrupalmeria.com\/en\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/","title":{"rendered":"\u00a1Incre\u00edble! Almer\u00eda exporta m\u00e1s tomate que el resto de provincias espa\u00f1olas juntas"},"content":{"rendered":"<h2><em>La provincia bati\u00f3 el r\u00e9cord hist\u00f3rico en el valor de esas exportaciones la campa\u00f1a pasada<\/em><\/h2>\n<p>&nbsp;<\/p>\n<p>En la reci\u00e9n concluida campa\u00f1a, Espa\u00f1a export\u00f3 un impresionante total de 598,28 millones de kilos de tomates, generando ingresos por valor de 1.143,15 millones de euros, con un precio promedio de 1,91 \u20ac por kilo, seg\u00fan datos proporcionados por Hortoinfo. Almer\u00eda encabez\u00f3 la lista como la provincia l\u00edder, contribuyendo con el 60,69% del volumen total de exportaciones de Espa\u00f1a, enviando 363,12 millones de kilos por un valor de 674,04 millones de euros, a un precio medio de 1,86 \u20ac por kilo. A pesar de estos logros, la provincia disminuy\u00f3 sus exportaciones de tomates en un 24% en las \u00faltimas cinco campa\u00f1as.<\/p>\n<p>Murcia, por su parte, export\u00f3 60,72 millones de kilos de tomates durante la campa\u00f1a, equivalente al 10,15% del total espa\u00f1ol, generando 111,96 millones de euros con un precio promedio de 1,84 \u20ac por kilo. Sin embargo, ha experimentado una disminuci\u00f3n del 32% en sus exportaciones de tomates desde la campa\u00f1a 2018\/2019.<\/p>\n<p>Granada se ubic\u00f3 en la tercera posici\u00f3n, con un volumen de 55,59 millones de kilos exportados, representando el 9,29% del total espa\u00f1ol. Estas exportaciones tuvieron un valor de 138,49 millones de euros y un precio medio de 2,49 \u20ac por kilo. Granada ha logrado aumentar sus exportaciones de tomates en un 3% en las \u00faltimas cinco campa\u00f1as.<\/p>\n<h3><strong>\u00bfA d\u00f3nde fue a parar el tomate almeriense?<\/strong><\/h3>\n<p>Alemania lider\u00f3 la lista de pa\u00edses receptores de las exportaciones de tomates de Almer\u00eda en la campa\u00f1a 2022\/23, con la adquisici\u00f3n de 118,89 millones de kilos, valorados en 235,57 millones de euros, a un precio promedio de 1,98 \u20ac por kilo. Francia ocup\u00f3 el segundo lugar con 45,26 millones de kilos de tomates a un precio medio de 1,52 \u20ac por kilo, mientras que Pa\u00edses Bajos y Reino Unido se situaron en tercer y cuarto lugar, respectivamente, en t\u00e9rminos de volumen y valor de las exportaciones de tomates desde Almer\u00eda. Portugal complet\u00f3 la lista como el quinto pa\u00eds receptor, con 16,8 millones de kilos de tomate y un precio promedio de 1,33 \u20ac por kilo.<\/p>\n<p>&nbsp;<\/p>\n<p>Source: <a href=\"https:\/\/www.freshplaza.es\/article\/9572535\/seis-de-cada-diez-tomates-espanoles-exportados-la-campana-pasada-procedieron-de-almeria\/\">Fresh Plaza<\/a><\/p>\n<p><a href=\"https:\/\/agrupalmeria.com\/en\/tag\/exportacion\/\">Otras noticias sobre exportaci\u00f3n<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>La provincia bati\u00f3 el r\u00e9cord hist\u00f3rico en el valor de esas exportaciones la campa\u00f1a pasada &nbsp; En la reci\u00e9n concluida campa\u00f1a, Espa\u00f1a export\u00f3 un impresionante total de 598,28 millones de kilos de tomates, generando ingresos por valor de 1.143,15 millones de euros, con un precio promedio de 1,91 \u20ac por kilo, seg\u00fan datos proporcionados por &hellip; <\/p>\n<p class=\"more-link-wrap\"><a href=\"https:\/\/agrupalmeria.com\/en\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/\" class=\"more-link\">Read More<span class=\"screen-reader-text\"> \u00ab\u00a1Incre\u00edble! Almer\u00eda exporta m\u00e1s tomate que el resto de provincias espa\u00f1olas juntas\u00bb<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":4638,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","footnotes":""},"categories":[85,84],"tags":[148,92,108,182,328,101],"class_list":["post-4636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-mercado","tag-agricultura","tag-almeria","tag-exportacion","tag-hortalizas","tag-subastadetomate","tag-tomate"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.9 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Almer\u00eda exporta m\u00e1s tomate que el resto de provincias espa\u00f1olas<\/title>\n<meta name=\"description\" content=\"La provincia de Almer\u00eda bati\u00f3 el r\u00e9cord hist\u00f3rico en el valor de las exportaciones de tomate la campa\u00f1a pasada\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupalmeria.com\/en\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Incre\u00edble! Almer\u00eda exporta m\u00e1s tomate que el resto de provincias espa\u00f1olas juntas\" \/>\n<meta property=\"og:description\" content=\"La provincia de Almer\u00eda bati\u00f3 el r\u00e9cord hist\u00f3rico en el valor de las exportaciones de tomate la campa\u00f1a pasada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupalmeria.com\/en\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrupalmer\u00eda\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-08T11:56:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-17T13:17:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2024\/01\/almeria-exporta-mas-que-toda-espana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1848\" \/>\n\t<meta property=\"og:image:height\" content=\"1230\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"agrupacanada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"agrupacanada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\\\/\"},\"author\":{\"name\":\"agrupacanada\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#\\\/schema\\\/person\\\/222c8c177ed35895570b6dccfdf53704\"},\"headline\":\"\u00a1Incre\u00edble! Almer\u00eda exporta m\u00e1s tomate que el resto de provincias espa\u00f1olas juntas\",\"datePublished\":\"2023-11-08T11:56:15+00:00\",\"dateModified\":\"2024-01-17T13:17:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\\\/\"},\"wordCount\":368,\"publisher\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/almeria-exporta-mas-que-toda-espana.jpg\",\"keywords\":[\"agricultura\",\"almeria\",\"exportacion\",\"hortalizas\",\"subastadetomate\",\"tomate\"],\"articleSection\":[\"Actualidad\",\"Mercado\"],\"inLanguage\":\"en-GB\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\\\/\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\\\/\",\"name\":\"Almer\u00eda exporta m\u00e1s tomate que el resto de provincias espa\u00f1olas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/almeria-exporta-mas-que-toda-espana.jpg\",\"datePublished\":\"2023-11-08T11:56:15+00:00\",\"dateModified\":\"2024-01-17T13:17:28+00:00\",\"description\":\"La provincia de Almer\u00eda bati\u00f3 el r\u00e9cord hist\u00f3rico en el valor de las exportaciones de tomate la campa\u00f1a pasada\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agrupalmeria.com\\\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/almeria-exporta-mas-que-toda-espana.jpg\",\"contentUrl\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/almeria-exporta-mas-que-toda-espana.jpg\",\"width\":1848,\"height\":1230,\"caption\":\"almeria exporta mas tomate que toda espa\u00f1a\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agrupalmeria.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Incre\u00edble! Almer\u00eda exporta m\u00e1s tomate que el resto de provincias espa\u00f1olas juntas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#website\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/\",\"name\":\"Agrupalmer\u00eda - El mejor tomate de Almer\u00eda\",\"description\":\"Subasta hortofrut\u00edcola con todas las variedades de tomate y el mejor tomate raf de Almer\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#organization\"},\"alternateName\":\"Agrupalmer\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agrupalmeria.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#organization\",\"name\":\"Agrupalmer\u00eda\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-logotipo-agrupalmeria-color.png\",\"contentUrl\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-logotipo-agrupalmeria-color.png\",\"width\":5924,\"height\":1184,\"caption\":\"Agrupalmer\u00eda\"},\"image\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#\\\/schema\\\/person\\\/222c8c177ed35895570b6dccfdf53704\",\"name\":\"agrupacanada\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g\",\"caption\":\"agrupacanada\"},\"sameAs\":[\"https:\\\/\\\/agrupalmeria.com\"],\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/en\\\/author\\\/agrupacanada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Almer\u00eda exporta m\u00e1s tomate que el resto de provincias espa\u00f1olas","description":"La provincia de Almer\u00eda bati\u00f3 el r\u00e9cord hist\u00f3rico en el valor de las exportaciones de tomate la campa\u00f1a pasada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupalmeria.com\/en\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/","og_locale":"en_GB","og_type":"article","og_title":"\u00a1Incre\u00edble! Almer\u00eda exporta m\u00e1s tomate que el resto de provincias espa\u00f1olas juntas","og_description":"La provincia de Almer\u00eda bati\u00f3 el r\u00e9cord hist\u00f3rico en el valor de las exportaciones de tomate la campa\u00f1a pasada","og_url":"https:\/\/agrupalmeria.com\/en\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/","og_site_name":"Agrupalmer\u00eda","article_published_time":"2023-11-08T11:56:15+00:00","article_modified_time":"2024-01-17T13:17:28+00:00","og_image":[{"width":1848,"height":1230,"url":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2024\/01\/almeria-exporta-mas-que-toda-espana.jpg","type":"image\/jpeg"}],"author":"agrupacanada","twitter_card":"summary_large_image","twitter_misc":{"Written by":"agrupacanada","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/agrupalmeria.com\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/#article","isPartOf":{"@id":"https:\/\/agrupalmeria.com\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/"},"author":{"name":"agrupacanada","@id":"https:\/\/agrupalmeria.com\/#\/schema\/person\/222c8c177ed35895570b6dccfdf53704"},"headline":"\u00a1Incre\u00edble! Almer\u00eda exporta m\u00e1s tomate que el resto de provincias espa\u00f1olas juntas","datePublished":"2023-11-08T11:56:15+00:00","dateModified":"2024-01-17T13:17:28+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupalmeria.com\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/"},"wordCount":368,"publisher":{"@id":"https:\/\/agrupalmeria.com\/#organization"},"image":{"@id":"https:\/\/agrupalmeria.com\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2024\/01\/almeria-exporta-mas-que-toda-espana.jpg","keywords":["agricultura","almeria","exportacion","hortalizas","subastadetomate","tomate"],"articleSection":["Actualidad","Mercado"],"inLanguage":"en-GB"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/agrupalmeria.com\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/","url":"https:\/\/agrupalmeria.com\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/","name":"Almer\u00eda exporta m\u00e1s tomate que el resto de provincias espa\u00f1olas","isPartOf":{"@id":"https:\/\/agrupalmeria.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupalmeria.com\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/#primaryimage"},"image":{"@id":"https:\/\/agrupalmeria.com\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2024\/01\/almeria-exporta-mas-que-toda-espana.jpg","datePublished":"2023-11-08T11:56:15+00:00","dateModified":"2024-01-17T13:17:28+00:00","description":"La provincia de Almer\u00eda bati\u00f3 el r\u00e9cord hist\u00f3rico en el valor de las exportaciones de tomate la campa\u00f1a pasada","breadcrumb":{"@id":"https:\/\/agrupalmeria.com\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupalmeria.com\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agrupalmeria.com\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/#primaryimage","url":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2024\/01\/almeria-exporta-mas-que-toda-espana.jpg","contentUrl":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2024\/01\/almeria-exporta-mas-que-toda-espana.jpg","width":1848,"height":1230,"caption":"almeria exporta mas tomate que toda espa\u00f1a"},{"@type":"BreadcrumbList","@id":"https:\/\/agrupalmeria.com\/increible-almeria-exporta-mas-tomate-que-el-resto-de-provincias-espanolas-juntas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupalmeria.com\/"},{"@type":"ListItem","position":2,"name":"\u00a1Incre\u00edble! Almer\u00eda exporta m\u00e1s tomate que el resto de provincias espa\u00f1olas juntas"}]},{"@type":"WebSite","@id":"https:\/\/agrupalmeria.com\/#website","url":"https:\/\/agrupalmeria.com\/","name":"Agrupalmer\u00eda - El mejor tomate de Almer\u00eda","description":"Subasta hortofrut\u00edcola con todas las variedades de tomate y el mejor tomate raf de Almer\u00eda","publisher":{"@id":"https:\/\/agrupalmeria.com\/#organization"},"alternateName":"Agrupalmer\u00eda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupalmeria.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/agrupalmeria.com\/#organization","name":"Agrupalmer\u00eda","url":"https:\/\/agrupalmeria.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agrupalmeria.com\/#\/schema\/logo\/image\/","url":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2021\/11\/cropped-logotipo-agrupalmeria-color.png","contentUrl":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2021\/11\/cropped-logotipo-agrupalmeria-color.png","width":5924,"height":1184,"caption":"Agrupalmer\u00eda"},"image":{"@id":"https:\/\/agrupalmeria.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/agrupalmeria.com\/#\/schema\/person\/222c8c177ed35895570b6dccfdf53704","name":"agrupacanada","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g","caption":"agrupacanada"},"sameAs":["https:\/\/agrupalmeria.com"],"url":"https:\/\/agrupalmeria.com\/en\/author\/agrupacanada\/"}]}},"_links":{"self":[{"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/posts\/4636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/comments?post=4636"}],"version-history":[{"count":1,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/posts\/4636\/revisions"}],"predecessor-version":[{"id":4639,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/posts\/4636\/revisions\/4639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/media\/4638"}],"wp:attachment":[{"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/media?parent=4636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/categories?post=4636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/tags?post=4636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}