{"id":4375,"date":"2023-02-02T20:58:18","date_gmt":"2023-02-02T20:58:18","guid":{"rendered":"https:\/\/agrupalmeria.com\/?p=4375"},"modified":"2023-02-02T20:58:18","modified_gmt":"2023-02-02T20:58:18","slug":"boom-joven-del-emprendimiento-agrario-almeriense","status":"publish","type":"post","link":"https:\/\/agrupalmeria.com\/en\/boom-joven-del-emprendimiento-agrario-almeriense\/","title":{"rendered":"`BOOM\u2019 joven del emprendimiento agrario almeriense"},"content":{"rendered":"<h2><em>\u00a1Un soplo de aire fresco! Las ayudas de la Junta \u00a1quintuplican! el n\u00famero de nuevos profesionales del sector agro almeriense con 800 nuevos j\u00f3venes emprendedores que se incorporan al campo almeriense<\/em><\/h2>\n<p>&nbsp;<\/p>\n<p>La apuesta por los nuevos profesionales del sector agro almeriense est\u00e1 clara: que sean j\u00f3venes emprendedores con formaci\u00f3n y muchas ganas de seguir mejorando a\u00fan m\u00e1s si cabe el modelo de agricultura almeriense.<\/p>\n<p>Hasta 800 j\u00f3venes almerienses se han beneficiado de las ayudas que la Junta de Andaluc\u00eda ha entregado a j\u00f3venes agricultores y ganaderos de las provincias de Almer\u00eda, Granada y Ja\u00e9n, que entran a formar parte de los 4.770 nuevos profesionales del campo.<\/p>\n<p>En Agrupalmer\u00eda tambi\u00e9n impulsamos a los j\u00f3venes al sector agrario y con nosotros se encuentra un equipo en el que ellos muestran un gran compromiso y r\u00e1pido aprendizaje. Junto a ellos, los m\u00e1s experimentados del sector, los especialistas. Unidos luchamos por hacer que os lleguen a casa <strong><u><a href=\"https:\/\/agrupalmeria.com\/en\/categorias-tomates\/\">los mejores tomates de Almer\u00eda<\/a>.<\/u><\/strong><\/p>\n<h3><strong>\u00a1La agricultura almeriense 5 veces \u201cm\u00e1s joven\u201d que el a\u00f1o pasado!<\/strong><\/h3>\n<p>Esta cifra de 800 nuevos profesionales del campo en Almer\u00eda quintuplica la cifra del a\u00f1o anterior, 146 j\u00f3venes, demostrando as\u00ed que cada vez es mayor la apuesta de los j\u00f3venes por la agricultura. Adem\u00e1s, aumenta tambi\u00e9n el n\u00famero de j\u00f3venes que deciden `aventurarse\u2019 en el mundo empresarial por la agricultura de su tierra.<\/p>\n<p>La propia consejera de Agricultura, Pesca, Agua y Desarrollo Rural, Carmen Crespo, ha felicitado a nuestra provincia y a los emprendedores, a los que considera m\u00e1s que merecedores de estas ayudas. \u201cNo es m\u00e9rito de la Junta de Andaluc\u00eda por poner en marcha estas ayudas sino m\u00e9rito vuestro, que sois los que con esfuerzo y recursos propios pon\u00e9is en marcha nuevos negocios\u201d, explic\u00f3 en sus <a href=\"https:\/\/www.almerianoticias.es\/la-junta-propicia-con-sus-ayudas-que-mas-de-800-jovenes-agricultores-y-ganaderos-se-incorporen-en-almeria\/\">declaraciones durante el acto de entrega de las ayudas en la Delegaci\u00f3n del Gobierno<\/a>.<\/p>\n<h3><strong>La base de la econom\u00eda andaluza es el agro<\/strong><\/h3>\n<p>En Agrupalmer\u00eda nos sentimos protagonistas de que el pasado, el presente y, sobre todo, el futuro de la econom\u00eda andaluza tenga su base principal en la agricultura, y apostamos por el esfuerzo y la dedicaci\u00f3n de cada uno de los agricultores, ayudando a distribuir y hacer llegar su producto a cualquier lugar, un producto que ya es reconocido en todo el mundo.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a1Un soplo de aire fresco! Las ayudas de la Junta \u00a1quintuplican! el n\u00famero de nuevos profesionales del sector agro almeriense con 800 nuevos j\u00f3venes emprendedores que se incorporan al campo almeriense &nbsp; La apuesta por los nuevos profesionales del sector agro almeriense est\u00e1 clara: que sean j\u00f3venes emprendedores con formaci\u00f3n y muchas ganas de seguir &hellip; <\/p>\n<p class=\"more-link-wrap\"><a href=\"https:\/\/agrupalmeria.com\/en\/boom-joven-del-emprendimiento-agrario-almeriense\/\" class=\"more-link\">Read More<span class=\"screen-reader-text\"> \u00ab`BOOM\u2019 joven del emprendimiento agrario almeriense\u00bb<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":4377,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","footnotes":""},"categories":[85,105,86,81],"tags":[99,148,102,92,194,180],"class_list":["post-4375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-agricultores","category-blog","category-sector","tag-agricultores","tag-agricultura","tag-agrupalmeria","tag-almeria","tag-emprendimiento","tag-sector-agrario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.9 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>`BOOM\u2019 joven del emprendimiento agrario almeriense<\/title>\n<meta name=\"description\" content=\"Las ayudas de la Junta quintuplican el n\u00famero de nuevos profesionales del sector agro almeriense con 800 nuevos j\u00f3venes emprendedores\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupalmeria.com\/en\/boom-joven-del-emprendimiento-agrario-almeriense\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"`BOOM\u2019 joven del emprendimiento agrario almeriense\" \/>\n<meta property=\"og:description\" content=\"Las ayudas de la Junta quintuplican el n\u00famero de nuevos profesionales del sector agro almeriense con 800 nuevos j\u00f3venes emprendedores\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupalmeria.com\/en\/boom-joven-del-emprendimiento-agrario-almeriense\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrupalmer\u00eda\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-02T20:58:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2023\/02\/acto-de-entrega-de-las-ayudas-a-jovenes-agricultores-almerienses.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"agrupacanada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"agrupacanada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/boom-joven-del-emprendimiento-agrario-almeriense\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/boom-joven-del-emprendimiento-agrario-almeriense\\\/\"},\"author\":{\"name\":\"agrupacanada\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#\\\/schema\\\/person\\\/222c8c177ed35895570b6dccfdf53704\"},\"headline\":\"`BOOM\u2019 joven del emprendimiento agrario almeriense\",\"datePublished\":\"2023-02-02T20:58:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/boom-joven-del-emprendimiento-agrario-almeriense\\\/\"},\"wordCount\":410,\"publisher\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/boom-joven-del-emprendimiento-agrario-almeriense\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/acto-de-entrega-de-las-ayudas-a-jovenes-agricultores-almerienses.jpg\",\"keywords\":[\"agricultores\",\"agricultura\",\"agrupalmeria\",\"almeria\",\"emprendimiento\",\"sector agrario\"],\"articleSection\":[\"Actualidad\",\"agricultores\",\"Blog\",\"Sector\"],\"inLanguage\":\"en-GB\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/boom-joven-del-emprendimiento-agrario-almeriense\\\/\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/boom-joven-del-emprendimiento-agrario-almeriense\\\/\",\"name\":\"`BOOM\u2019 joven del emprendimiento agrario almeriense\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/boom-joven-del-emprendimiento-agrario-almeriense\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/boom-joven-del-emprendimiento-agrario-almeriense\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/acto-de-entrega-de-las-ayudas-a-jovenes-agricultores-almerienses.jpg\",\"datePublished\":\"2023-02-02T20:58:18+00:00\",\"description\":\"Las ayudas de la Junta quintuplican el n\u00famero de nuevos profesionales del sector agro almeriense con 800 nuevos j\u00f3venes emprendedores\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/boom-joven-del-emprendimiento-agrario-almeriense\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agrupalmeria.com\\\/boom-joven-del-emprendimiento-agrario-almeriense\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/boom-joven-del-emprendimiento-agrario-almeriense\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/acto-de-entrega-de-las-ayudas-a-jovenes-agricultores-almerienses.jpg\",\"contentUrl\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/acto-de-entrega-de-las-ayudas-a-jovenes-agricultores-almerienses.jpg\",\"width\":700,\"height\":525,\"caption\":\"ayudas jovenes agricultores\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/boom-joven-del-emprendimiento-agrario-almeriense\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agrupalmeria.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"`BOOM\u2019 joven del emprendimiento agrario almeriense\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#website\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/\",\"name\":\"Agrupalmer\u00eda - El mejor tomate de Almer\u00eda\",\"description\":\"Subasta hortofrut\u00edcola con todas las variedades de tomate y el mejor tomate raf de Almer\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#organization\"},\"alternateName\":\"Agrupalmer\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agrupalmeria.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#organization\",\"name\":\"Agrupalmer\u00eda\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-logotipo-agrupalmeria-color.png\",\"contentUrl\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-logotipo-agrupalmeria-color.png\",\"width\":5924,\"height\":1184,\"caption\":\"Agrupalmer\u00eda\"},\"image\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#\\\/schema\\\/person\\\/222c8c177ed35895570b6dccfdf53704\",\"name\":\"agrupacanada\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g\",\"caption\":\"agrupacanada\"},\"sameAs\":[\"https:\\\/\\\/agrupalmeria.com\"],\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/en\\\/author\\\/agrupacanada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"`BOOM\u2019 joven del emprendimiento agrario almeriense","description":"Las ayudas de la Junta quintuplican el n\u00famero de nuevos profesionales del sector agro almeriense con 800 nuevos j\u00f3venes emprendedores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupalmeria.com\/en\/boom-joven-del-emprendimiento-agrario-almeriense\/","og_locale":"en_GB","og_type":"article","og_title":"`BOOM\u2019 joven del emprendimiento agrario almeriense","og_description":"Las ayudas de la Junta quintuplican el n\u00famero de nuevos profesionales del sector agro almeriense con 800 nuevos j\u00f3venes emprendedores","og_url":"https:\/\/agrupalmeria.com\/en\/boom-joven-del-emprendimiento-agrario-almeriense\/","og_site_name":"Agrupalmer\u00eda","article_published_time":"2023-02-02T20:58:18+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2023\/02\/acto-de-entrega-de-las-ayudas-a-jovenes-agricultores-almerienses.jpg","type":"image\/jpeg"}],"author":"agrupacanada","twitter_card":"summary_large_image","twitter_misc":{"Written by":"agrupacanada","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/agrupalmeria.com\/boom-joven-del-emprendimiento-agrario-almeriense\/#article","isPartOf":{"@id":"https:\/\/agrupalmeria.com\/boom-joven-del-emprendimiento-agrario-almeriense\/"},"author":{"name":"agrupacanada","@id":"https:\/\/agrupalmeria.com\/#\/schema\/person\/222c8c177ed35895570b6dccfdf53704"},"headline":"`BOOM\u2019 joven del emprendimiento agrario almeriense","datePublished":"2023-02-02T20:58:18+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupalmeria.com\/boom-joven-del-emprendimiento-agrario-almeriense\/"},"wordCount":410,"publisher":{"@id":"https:\/\/agrupalmeria.com\/#organization"},"image":{"@id":"https:\/\/agrupalmeria.com\/boom-joven-del-emprendimiento-agrario-almeriense\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2023\/02\/acto-de-entrega-de-las-ayudas-a-jovenes-agricultores-almerienses.jpg","keywords":["agricultores","agricultura","agrupalmeria","almeria","emprendimiento","sector agrario"],"articleSection":["Actualidad","agricultores","Blog","Sector"],"inLanguage":"en-GB"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/agrupalmeria.com\/boom-joven-del-emprendimiento-agrario-almeriense\/","url":"https:\/\/agrupalmeria.com\/boom-joven-del-emprendimiento-agrario-almeriense\/","name":"`BOOM\u2019 joven del emprendimiento agrario almeriense","isPartOf":{"@id":"https:\/\/agrupalmeria.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupalmeria.com\/boom-joven-del-emprendimiento-agrario-almeriense\/#primaryimage"},"image":{"@id":"https:\/\/agrupalmeria.com\/boom-joven-del-emprendimiento-agrario-almeriense\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2023\/02\/acto-de-entrega-de-las-ayudas-a-jovenes-agricultores-almerienses.jpg","datePublished":"2023-02-02T20:58:18+00:00","description":"Las ayudas de la Junta quintuplican el n\u00famero de nuevos profesionales del sector agro almeriense con 800 nuevos j\u00f3venes emprendedores","breadcrumb":{"@id":"https:\/\/agrupalmeria.com\/boom-joven-del-emprendimiento-agrario-almeriense\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupalmeria.com\/boom-joven-del-emprendimiento-agrario-almeriense\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agrupalmeria.com\/boom-joven-del-emprendimiento-agrario-almeriense\/#primaryimage","url":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2023\/02\/acto-de-entrega-de-las-ayudas-a-jovenes-agricultores-almerienses.jpg","contentUrl":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2023\/02\/acto-de-entrega-de-las-ayudas-a-jovenes-agricultores-almerienses.jpg","width":700,"height":525,"caption":"ayudas jovenes agricultores"},{"@type":"BreadcrumbList","@id":"https:\/\/agrupalmeria.com\/boom-joven-del-emprendimiento-agrario-almeriense\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupalmeria.com\/"},{"@type":"ListItem","position":2,"name":"`BOOM\u2019 joven del emprendimiento agrario almeriense"}]},{"@type":"WebSite","@id":"https:\/\/agrupalmeria.com\/#website","url":"https:\/\/agrupalmeria.com\/","name":"Agrupalmer\u00eda - El mejor tomate de Almer\u00eda","description":"Subasta hortofrut\u00edcola con todas las variedades de tomate y el mejor tomate raf de Almer\u00eda","publisher":{"@id":"https:\/\/agrupalmeria.com\/#organization"},"alternateName":"Agrupalmer\u00eda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupalmeria.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/agrupalmeria.com\/#organization","name":"Agrupalmer\u00eda","url":"https:\/\/agrupalmeria.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agrupalmeria.com\/#\/schema\/logo\/image\/","url":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2021\/11\/cropped-logotipo-agrupalmeria-color.png","contentUrl":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2021\/11\/cropped-logotipo-agrupalmeria-color.png","width":5924,"height":1184,"caption":"Agrupalmer\u00eda"},"image":{"@id":"https:\/\/agrupalmeria.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/agrupalmeria.com\/#\/schema\/person\/222c8c177ed35895570b6dccfdf53704","name":"agrupacanada","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g","caption":"agrupacanada"},"sameAs":["https:\/\/agrupalmeria.com"],"url":"https:\/\/agrupalmeria.com\/en\/author\/agrupacanada\/"}]}},"_links":{"self":[{"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/posts\/4375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/comments?post=4375"}],"version-history":[{"count":1,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/posts\/4375\/revisions"}],"predecessor-version":[{"id":4378,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/posts\/4375\/revisions\/4378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/media\/4377"}],"wp:attachment":[{"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/media?parent=4375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/categories?post=4375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/tags?post=4375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}