{"id":4260,"date":"2022-09-15T13:12:08","date_gmt":"2022-09-15T13:12:08","guid":{"rendered":"https:\/\/agrupalmeria.com\/?p=4260"},"modified":"2022-09-15T13:12:08","modified_gmt":"2022-09-15T13:12:08","slug":"el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia","status":"publish","type":"post","link":"https:\/\/agrupalmeria.com\/en\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/","title":{"rendered":"El tomate supera todas las expectativas y copa los cultivos de la provincia"},"content":{"rendered":"<h2><em>Cultivos como el pimiento o el calabac\u00edn pierden su peso en la ocupaci\u00f3n de terrenos de cultivo en favor del tomate, que vuelve a liderar los campos almerienses<\/em><\/h2>\n<p>&nbsp;<\/p>\n<p>La organizaci\u00f3n agraria de <a href=\"https:\/\/asajaalmeria.org\/\">Asaja &#8211; Almer\u00eda<\/a> calcula en <strong>un 15% el incremento de extensi\u00f3n del cultivo de tomate<\/strong> para esta campa\u00f1a con respecto a la temporada pasada. El incremento de los precios conseguido en la pasada campa\u00f1a ha animado a los agricultores a recuperar un cultivo que hab\u00eda perdido parte de su liderazgo en los \u00faltimos a\u00f1os, en pos de otros cultivos.<\/p>\n<p>En la \u00faltima d\u00e9cada los agricultores se hab\u00edan centrado algo m\u00e1s en cultivos como el pimiento o el calabac\u00edn, debido a la inestabilidad de precios del tomate a\u00f1os atr\u00e1s, pero con el incremento de precios del \u00faltimo a\u00f1o la situaci\u00f3n se ha revertido a favor de este cultivo.<\/p>\n<h3><strong><a href=\"https:\/\/agrupalmeria.com\/en\/tomate-pera\/\">Tomatoes<\/a> and <a href=\"https:\/\/agrupalmeria.com\/en\/tomate-rama\/\">tomate rama<\/a>, los m\u00e1s vers\u00e1tiles para los agricultores<\/strong><\/h3>\n<p>En cuanto a las variedades m\u00e1s cultivadas en este inicio de campa\u00f1a, desde la organizaci\u00f3n agraria destacan las especialidades de tomate pera y tomate rama debido a que son variedades mucho m\u00e1s vers\u00e1tiles para los agricultores.<\/p>\n<p>Agrupalmer\u00eda, como empresa hortofrut\u00edcola especializada en el mejor tomate de la provincia de Almer\u00eda, es consciente del gran crecimiento que el cultivo de tomate ha experimentado en esta campa\u00f1a y no pierde la oportunidad de ofrecer su servicio de subasta a todo agricultor que necesite dar salida a su producto. Una subasta <em>como las de siempre<\/em> con precio firme diario para nuestros productores que variar\u00e1 en funci\u00f3n de la oferta y la demanda.<\/p>\n<p><a href=\"https:\/\/agrupalmeria.com\/en\/contacto\/\">Contacta con Agrupalmer\u00eda<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Cultivos como el pimiento o el calabac\u00edn pierden su peso en la ocupaci\u00f3n de terrenos de cultivo en favor del tomate, que vuelve a liderar los campos almerienses &nbsp; La organizaci\u00f3n agraria de Asaja &#8211; Almer\u00eda calcula en un 15% el incremento de extensi\u00f3n del cultivo de tomate para esta campa\u00f1a con respecto a la &hellip; <\/p>\n<p class=\"more-link-wrap\"><a href=\"https:\/\/agrupalmeria.com\/en\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/\" class=\"more-link\">Read More<span class=\"screen-reader-text\"> \u00abEl tomate supera todas las expectativas y copa los cultivos de la provincia\u00bb<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":4262,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","footnotes":""},"categories":[85,84,81],"tags":[148,102,92,160,159,158,157,101],"class_list":["post-4260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-mercado","category-sector","tag-agricultura","tag-agrupalmeria","tag-almeria","tag-asaja","tag-cultivo","tag-lider-de-la-provincia","tag-lider-de-los-cultivos","tag-tomate"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.9 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El tomate supera todas las expectativas y copa los cultivos de la provincia - Agrupalmer\u00eda<\/title>\n<meta name=\"description\" content=\"el tomate vuelve a liderar los campos almerienses\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agrupalmeria.com\/en\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El tomate supera todas las expectativas y copa los cultivos de la provincia\" \/>\n<meta property=\"og:description\" content=\"el tomate vuelve a liderar los campos almerienses\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agrupalmeria.com\/en\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrupalmer\u00eda\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-15T13:12:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2022\/09\/cultivo_tomate_almeria_agricultura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"agrupacanada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"agrupacanada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\\\/\"},\"author\":{\"name\":\"agrupacanada\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#\\\/schema\\\/person\\\/222c8c177ed35895570b6dccfdf53704\"},\"headline\":\"El tomate supera todas las expectativas y copa los cultivos de la provincia\",\"datePublished\":\"2022-09-15T13:12:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\\\/\"},\"wordCount\":305,\"publisher\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cultivo_tomate_almeria_agricultura.jpg\",\"keywords\":[\"agricultura\",\"agrupalmeria\",\"almeria\",\"asaja\",\"cultivo\",\"lider de la provincia\",\"lider de los cultivos\",\"tomate\"],\"articleSection\":[\"Actualidad\",\"Mercado\",\"Sector\"],\"inLanguage\":\"en-GB\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\\\/\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\\\/\",\"name\":\"El tomate supera todas las expectativas y copa los cultivos de la provincia - Agrupalmer\u00eda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cultivo_tomate_almeria_agricultura.jpg\",\"datePublished\":\"2022-09-15T13:12:08+00:00\",\"description\":\"el tomate vuelve a liderar los campos almerienses\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agrupalmeria.com\\\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cultivo_tomate_almeria_agricultura.jpg\",\"contentUrl\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cultivo_tomate_almeria_agricultura.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"cultivo lider en almeria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agrupalmeria.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El tomate supera todas las expectativas y copa los cultivos de la provincia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#website\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/\",\"name\":\"Agrupalmer\u00eda - El mejor tomate de Almer\u00eda\",\"description\":\"Subasta hortofrut\u00edcola con todas las variedades de tomate y el mejor tomate raf de Almer\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#organization\"},\"alternateName\":\"Agrupalmer\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agrupalmeria.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#organization\",\"name\":\"Agrupalmer\u00eda\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-logotipo-agrupalmeria-color.png\",\"contentUrl\":\"https:\\\/\\\/agrupalmeria.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-logotipo-agrupalmeria-color.png\",\"width\":5924,\"height\":1184,\"caption\":\"Agrupalmer\u00eda\"},\"image\":{\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agrupalmeria.com\\\/#\\\/schema\\\/person\\\/222c8c177ed35895570b6dccfdf53704\",\"name\":\"agrupacanada\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g\",\"caption\":\"agrupacanada\"},\"sameAs\":[\"https:\\\/\\\/agrupalmeria.com\"],\"url\":\"https:\\\/\\\/agrupalmeria.com\\\/en\\\/author\\\/agrupacanada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El tomate supera todas las expectativas y copa los cultivos de la provincia - Agrupalmer\u00eda","description":"el tomate vuelve a liderar los campos almerienses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agrupalmeria.com\/en\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/","og_locale":"en_GB","og_type":"article","og_title":"El tomate supera todas las expectativas y copa los cultivos de la provincia","og_description":"el tomate vuelve a liderar los campos almerienses","og_url":"https:\/\/agrupalmeria.com\/en\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/","og_site_name":"Agrupalmer\u00eda","article_published_time":"2022-09-15T13:12:08+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2022\/09\/cultivo_tomate_almeria_agricultura.jpg","type":"image\/jpeg"}],"author":"agrupacanada","twitter_card":"summary_large_image","twitter_misc":{"Written by":"agrupacanada","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/agrupalmeria.com\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/#article","isPartOf":{"@id":"https:\/\/agrupalmeria.com\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/"},"author":{"name":"agrupacanada","@id":"https:\/\/agrupalmeria.com\/#\/schema\/person\/222c8c177ed35895570b6dccfdf53704"},"headline":"El tomate supera todas las expectativas y copa los cultivos de la provincia","datePublished":"2022-09-15T13:12:08+00:00","mainEntityOfPage":{"@id":"https:\/\/agrupalmeria.com\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/"},"wordCount":305,"publisher":{"@id":"https:\/\/agrupalmeria.com\/#organization"},"image":{"@id":"https:\/\/agrupalmeria.com\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2022\/09\/cultivo_tomate_almeria_agricultura.jpg","keywords":["agricultura","agrupalmeria","almeria","asaja","cultivo","lider de la provincia","lider de los cultivos","tomate"],"articleSection":["Actualidad","Mercado","Sector"],"inLanguage":"en-GB"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/agrupalmeria.com\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/","url":"https:\/\/agrupalmeria.com\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/","name":"El tomate supera todas las expectativas y copa los cultivos de la provincia - Agrupalmer\u00eda","isPartOf":{"@id":"https:\/\/agrupalmeria.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agrupalmeria.com\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/#primaryimage"},"image":{"@id":"https:\/\/agrupalmeria.com\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/#primaryimage"},"thumbnailUrl":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2022\/09\/cultivo_tomate_almeria_agricultura.jpg","datePublished":"2022-09-15T13:12:08+00:00","description":"el tomate vuelve a liderar los campos almerienses","breadcrumb":{"@id":"https:\/\/agrupalmeria.com\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agrupalmeria.com\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agrupalmeria.com\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/#primaryimage","url":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2022\/09\/cultivo_tomate_almeria_agricultura.jpg","contentUrl":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2022\/09\/cultivo_tomate_almeria_agricultura.jpg","width":1500,"height":1000,"caption":"cultivo lider en almeria"},{"@type":"BreadcrumbList","@id":"https:\/\/agrupalmeria.com\/el-tomate-supera-todas-las-expectativas-y-copa-los-cultivos-de-la-provincia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agrupalmeria.com\/"},{"@type":"ListItem","position":2,"name":"El tomate supera todas las expectativas y copa los cultivos de la provincia"}]},{"@type":"WebSite","@id":"https:\/\/agrupalmeria.com\/#website","url":"https:\/\/agrupalmeria.com\/","name":"Agrupalmer\u00eda - El mejor tomate de Almer\u00eda","description":"Subasta hortofrut\u00edcola con todas las variedades de tomate y el mejor tomate raf de Almer\u00eda","publisher":{"@id":"https:\/\/agrupalmeria.com\/#organization"},"alternateName":"Agrupalmer\u00eda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agrupalmeria.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/agrupalmeria.com\/#organization","name":"Agrupalmer\u00eda","url":"https:\/\/agrupalmeria.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agrupalmeria.com\/#\/schema\/logo\/image\/","url":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2021\/11\/cropped-logotipo-agrupalmeria-color.png","contentUrl":"https:\/\/agrupalmeria.com\/wp-content\/uploads\/2021\/11\/cropped-logotipo-agrupalmeria-color.png","width":5924,"height":1184,"caption":"Agrupalmer\u00eda"},"image":{"@id":"https:\/\/agrupalmeria.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/agrupalmeria.com\/#\/schema\/person\/222c8c177ed35895570b6dccfdf53704","name":"agrupacanada","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/999d1ccb0214f7d3a7bad71297580526bbe715de95600baf3bb81cacbbe52663?s=96&d=mm&r=g","caption":"agrupacanada"},"sameAs":["https:\/\/agrupalmeria.com"],"url":"https:\/\/agrupalmeria.com\/en\/author\/agrupacanada\/"}]}},"_links":{"self":[{"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/posts\/4260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/comments?post=4260"}],"version-history":[{"count":1,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/posts\/4260\/revisions"}],"predecessor-version":[{"id":4263,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/posts\/4260\/revisions\/4263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/media\/4262"}],"wp:attachment":[{"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/media?parent=4260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/categories?post=4260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrupalmeria.com\/en\/wp-json\/wp\/v2\/tags?post=4260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}